{"id":14660,"date":"2024-10-31T09:09:23","date_gmt":"2024-10-31T09:09:23","guid":{"rendered":"https:\/\/pimvendors.com\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\/"},"modified":"2024-10-31T09:09:23","modified_gmt":"2024-10-31T09:09:23","slug":"genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap","status":"publish","type":"post","link":"https:\/\/pimvendors.com\/nl\/pim-nl\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\/","title":{"rendered":"&#8220;GenAI Reign: How Young Buyers Are Revolutionizing B2B eCommerce&#8221; &#8211; Een boeiende verschuiving in het landschap"},"content":{"rendered":"<h2>Het veranderende landschap van B2B e-commerce: De opkomst van jonge kopers en AI<\/h2>\n<p>Het rapport van Forrester dat onlangs op ons bureau belandde, schetst een levendig beeld van de B2B eCommerce van morgen &#8211; een landschap dat sterk wordt be\u00efnvloed door de voorkeuren en het gedrag van jongere kopers die een grote invloed hebben op de aankoop van hoogwaardige artikelen en diensten voor hun bedrijven.<\/p>\n<p>Het verhaal heeft een diepgaande verschuiving ondergaan; het is niet langer de geleidelijke, voorspelbare evolutie van kooppatronen die we gewend zijn te volgen. Tegenwoordig hebben we het over een snelle transformatie die wordt aangewakkerd door jongeren en technologie. De jongere cohorten &#8211; behendig, technisch onderlegd en veeleisend wat betreft omnichannel aankoopopties &#8211; zijn de regels aan het herschrijven.  <\/p>\n<p>Ga maar na: 52% van de B2B-inkopers wereldwijd sluit regelmatig deals van miljoenen dollars af, waarbij ze deze omvangrijke transacties afhandelen via de accountvertegenwoordigers van verkopers. Dit is een belangrijke indicator van de digitale verkoopgolf die we in verschillende sectoren zien. <\/p>\n<p>Maar wat drijft deze aankooppatronen met name aan? Kunstmatige intelligentie, meer specifiek generatieve AI (genAI). Een overweldigende 92% van de inkopers die genAI gebruiken voor belangrijke aankopen, bevestigt dat het leidt tot &#8220;betere bedrijfsresultaten&#8221;. Het lijkt erop dat de AI-revolutie in B2B-aankopen niet op komst is; ze is er al en brengt een nieuw tijdperk van effici\u00ebntie en snelle transactie-uitwisselingen met zich mee.   <\/p>\n<p>Natuurlijk brengt verandering uitdagingen met zich mee. De reis is niet alleen maar snel internet en naadloze transacties &#8211; 96% van de jongere kopers is tot op zekere hoogte ontevreden over hun koopervaring, of dit nu te wijten is aan technische haperingen, een gebrekkige implementatie of een tekort aan DEI-initiatieven. <\/p>\n<p>Toch is het momentum om AI in de B2B inkoopruimte te omarmen onmiskenbaar. Een verbazingwekkende 94% van de inkopers die betrokken zijn bij miljoenentransacties maken al gebruik van de kracht van genAI of hebben plannen om het binnenkort te integreren. Interessant is dat een aanzienlijk deel van de AI-gebruikers de nadruk legt op het vermogen om de behoefte aan traditionele interacties tussen inkoper en verkoper te verminderen, het aantal uren onderzoek te verminderen en de voltooiing van aankopen te versnellen.  <\/p>\n<p>Deze gegevens wijzen niet alleen op trends, maar ook op een ware paradigmaverschuiving. Nu we zien dat jongere kopers hun dominantie op de markt laten gelden, zal de bredere PIM-sector (Product Information Management) zich waarschijnlijk moeten aanpassen. Snelle, gepersonaliseerde en sterk geautomatiseerde aankoopprocessen zullen de norm worden, waardoor PIM-systemen geavanceerder en AI-ge\u00efntegreerder moeten worden. De PIM-markt is klaar om te evolueren en biedt systemen die zijn uitgerust om te voldoen aan de vraag naar snelheid, nauwkeurigheid en uitgebreide gegevensverwerking die deze kopers en de AI waar ze van afhankelijk zijn, vereisen.   <\/p>\n<p>Kortom, de toekomst van B2B-inkoop is steeds digitaler, steeds autonomer en steeds dynamischer. Omarm de snelle stromingen van verandering of blijf achter op de kusten van veroudering. <\/p>\n<p>Voor meer inzichten kunt u het originele rapport en de context raadplegen op Digital Commerce 360.<\/p>\n<p>Bron: <a href=\"https:\/\/www.digitalcommerce360.com\/2024\/10\/23\/why-younger-b2b-buyers-are-calling-the-shots-online\/\" target=\"_blank\" rel=\"noopener\">Digital Commerce 360<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Het veranderende landschap van B2B e-commerce: De opkomst van jonge kopers en AI Het rapport van Forrester dat onlangs op ons bureau belandde, schetst een levendig beeld van de B2B&#8230;<\/p>\n","protected":false},"author":2,"featured_media":14652,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[118,92],"tags":[],"class_list":{"0":"post-14660","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nieuws-nl","8":"category-pim-nl"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;GenAI Reign: How Young Buyers Are Revolutionizing B2B eCommerce&quot; - Een boeiende verschuiving in het landschap - PIMvendors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pimvendors.com\/nl\/pim-nl\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;GenAI Reign: How Young Buyers Are Revolutionizing B2B eCommerce&quot; - Een boeiende verschuiving in het landschap - PIMvendors\" \/>\n<meta property=\"og:description\" content=\"Het veranderende landschap van B2B e-commerce: De opkomst van jonge kopers en AI Het rapport van Forrester dat onlangs op ons bureau belandde, schetst een levendig beeld van de B2B...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pimvendors.com\/nl\/pim-nl\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\/\" \/>\n<meta property=\"og:site_name\" content=\"PIMvendors\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-31T09:09:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pimvendors.com\/wp-content\/uploads\/0.8966361104815499-1024x585.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"585\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Stephan Spijkers\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pimvendors\" \/>\n<meta name=\"twitter:site\" content=\"@pimvendors\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"Stephan Spijkers\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pimvendors.com\\\/nl\\\/pim-nl\\\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pimvendors.com\\\/nl\\\/pim-nl\\\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\\\/\"},\"author\":{\"name\":\"Stephan Spijkers\",\"@id\":\"https:\\\/\\\/pimvendors.com\\\/#\\\/schema\\\/person\\\/1999987909349712f525ba0b70ff96c9\"},\"headline\":\"&#8220;GenAI Reign: How Young Buyers Are Revolutionizing B2B eCommerce&#8221; &#8211; Een boeiende verschuiving in het landschap\",\"datePublished\":\"2024-10-31T09:09:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pimvendors.com\\\/nl\\\/pim-nl\\\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\\\/\"},\"wordCount\":515,\"publisher\":{\"@id\":\"https:\\\/\\\/pimvendors.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/pimvendors.com\\\/nl\\\/pim-nl\\\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pimvendors.com\\\/wp-content\\\/uploads\\\/0.8966361104815499.png\",\"articleSection\":[\"Nieuws\",\"PIM\"],\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pimvendors.com\\\/nl\\\/pim-nl\\\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\\\/\",\"url\":\"https:\\\/\\\/pimvendors.com\\\/nl\\\/pim-nl\\\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\\\/\",\"name\":\"\\\"GenAI Reign: How Young Buyers Are Revolutionizing B2B eCommerce\\\" - Een boeiende verschuiving in het landschap - PIMvendors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pimvendors.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pimvendors.com\\\/nl\\\/pim-nl\\\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pimvendors.com\\\/nl\\\/pim-nl\\\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pimvendors.com\\\/wp-content\\\/uploads\\\/0.8966361104815499.png\",\"datePublished\":\"2024-10-31T09:09:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pimvendors.com\\\/nl\\\/pim-nl\\\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pimvendors.com\\\/nl\\\/pim-nl\\\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/pimvendors.com\\\/nl\\\/pim-nl\\\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pimvendors.com\\\/wp-content\\\/uploads\\\/0.8966361104815499.png\",\"contentUrl\":\"https:\\\/\\\/pimvendors.com\\\/wp-content\\\/uploads\\\/0.8966361104815499.png\",\"width\":1792,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pimvendors.com\\\/nl\\\/pim-nl\\\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pimvendors.com\\\/nl\\\/thuis\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;GenAI Reign: How Young Buyers Are Revolutionizing B2B eCommerce&#8221; &#8211; Een boeiende verschuiving in het landschap\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pimvendors.com\\\/#website\",\"url\":\"https:\\\/\\\/pimvendors.com\\\/\",\"name\":\"PIMvendors\",\"description\":\"Independent PIM Selection\",\"publisher\":{\"@id\":\"https:\\\/\\\/pimvendors.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pimvendors.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pimvendors.com\\\/#organization\",\"name\":\"PIMvendors\",\"url\":\"https:\\\/\\\/pimvendors.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/pimvendors.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pimvendors.com\\\/wp-content\\\/uploads\\\/cropped-favicon-1.png\",\"contentUrl\":\"https:\\\/\\\/pimvendors.com\\\/wp-content\\\/uploads\\\/cropped-favicon-1.png\",\"width\":512,\"height\":512,\"caption\":\"PIMvendors\"},\"image\":{\"@id\":\"https:\\\/\\\/pimvendors.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/pimvendors\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pimvendors\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pimvendors.com\\\/#\\\/schema\\\/person\\\/1999987909349712f525ba0b70ff96c9\",\"name\":\"Stephan Spijkers\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c74256c80db9607fe0f19adc6f6aa84098ac8b38ed73c93208633e68f653c8c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c74256c80db9607fe0f19adc6f6aa84098ac8b38ed73c93208633e68f653c8c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c74256c80db9607fe0f19adc6f6aa84098ac8b38ed73c93208633e68f653c8c?s=96&d=mm&r=g\",\"caption\":\"Stephan Spijkers\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"GenAI Reign: How Young Buyers Are Revolutionizing B2B eCommerce\" - Een boeiende verschuiving in het landschap - PIMvendors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pimvendors.com\/nl\/pim-nl\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\/","og_locale":"nl_NL","og_type":"article","og_title":"\"GenAI Reign: How Young Buyers Are Revolutionizing B2B eCommerce\" - Een boeiende verschuiving in het landschap - PIMvendors","og_description":"Het veranderende landschap van B2B e-commerce: De opkomst van jonge kopers en AI Het rapport van Forrester dat onlangs op ons bureau belandde, schetst een levendig beeld van de B2B...","og_url":"https:\/\/pimvendors.com\/nl\/pim-nl\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\/","og_site_name":"PIMvendors","article_published_time":"2024-10-31T09:09:23+00:00","og_image":[{"width":1024,"height":585,"url":"https:\/\/pimvendors.com\/wp-content\/uploads\/0.8966361104815499-1024x585.png","type":"image\/png"}],"author":"Stephan Spijkers","twitter_card":"summary_large_image","twitter_creator":"@pimvendors","twitter_site":"@pimvendors","twitter_misc":{"Geschreven door":"Stephan Spijkers","Geschatte leestijd":"2 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pimvendors.com\/nl\/pim-nl\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\/#article","isPartOf":{"@id":"https:\/\/pimvendors.com\/nl\/pim-nl\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\/"},"author":{"name":"Stephan Spijkers","@id":"https:\/\/pimvendors.com\/#\/schema\/person\/1999987909349712f525ba0b70ff96c9"},"headline":"&#8220;GenAI Reign: How Young Buyers Are Revolutionizing B2B eCommerce&#8221; &#8211; Een boeiende verschuiving in het landschap","datePublished":"2024-10-31T09:09:23+00:00","mainEntityOfPage":{"@id":"https:\/\/pimvendors.com\/nl\/pim-nl\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\/"},"wordCount":515,"publisher":{"@id":"https:\/\/pimvendors.com\/#organization"},"image":{"@id":"https:\/\/pimvendors.com\/nl\/pim-nl\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\/#primaryimage"},"thumbnailUrl":"https:\/\/pimvendors.com\/wp-content\/uploads\/0.8966361104815499.png","articleSection":["Nieuws","PIM"],"inLanguage":"nl-NL"},{"@type":"WebPage","@id":"https:\/\/pimvendors.com\/nl\/pim-nl\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\/","url":"https:\/\/pimvendors.com\/nl\/pim-nl\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\/","name":"\"GenAI Reign: How Young Buyers Are Revolutionizing B2B eCommerce\" - Een boeiende verschuiving in het landschap - PIMvendors","isPartOf":{"@id":"https:\/\/pimvendors.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pimvendors.com\/nl\/pim-nl\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\/#primaryimage"},"image":{"@id":"https:\/\/pimvendors.com\/nl\/pim-nl\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\/#primaryimage"},"thumbnailUrl":"https:\/\/pimvendors.com\/wp-content\/uploads\/0.8966361104815499.png","datePublished":"2024-10-31T09:09:23+00:00","breadcrumb":{"@id":"https:\/\/pimvendors.com\/nl\/pim-nl\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pimvendors.com\/nl\/pim-nl\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/pimvendors.com\/nl\/pim-nl\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\/#primaryimage","url":"https:\/\/pimvendors.com\/wp-content\/uploads\/0.8966361104815499.png","contentUrl":"https:\/\/pimvendors.com\/wp-content\/uploads\/0.8966361104815499.png","width":1792,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/pimvendors.com\/nl\/pim-nl\/genai-reign-how-young-buyers-are-revolutionizing-b2b-ecommerce-een-boeiende-verschuiving-in-het-landschap\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pimvendors.com\/nl\/thuis\/"},{"@type":"ListItem","position":2,"name":"&#8220;GenAI Reign: How Young Buyers Are Revolutionizing B2B eCommerce&#8221; &#8211; Een boeiende verschuiving in het landschap"}]},{"@type":"WebSite","@id":"https:\/\/pimvendors.com\/#website","url":"https:\/\/pimvendors.com\/","name":"PIMvendors","description":"Independent PIM Selection","publisher":{"@id":"https:\/\/pimvendors.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pimvendors.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/pimvendors.com\/#organization","name":"PIMvendors","url":"https:\/\/pimvendors.com\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/pimvendors.com\/#\/schema\/logo\/image\/","url":"https:\/\/pimvendors.com\/wp-content\/uploads\/cropped-favicon-1.png","contentUrl":"https:\/\/pimvendors.com\/wp-content\/uploads\/cropped-favicon-1.png","width":512,"height":512,"caption":"PIMvendors"},"image":{"@id":"https:\/\/pimvendors.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/pimvendors","https:\/\/www.linkedin.com\/company\/pimvendors\/"]},{"@type":"Person","@id":"https:\/\/pimvendors.com\/#\/schema\/person\/1999987909349712f525ba0b70ff96c9","name":"Stephan Spijkers","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/8c74256c80db9607fe0f19adc6f6aa84098ac8b38ed73c93208633e68f653c8c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8c74256c80db9607fe0f19adc6f6aa84098ac8b38ed73c93208633e68f653c8c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8c74256c80db9607fe0f19adc6f6aa84098ac8b38ed73c93208633e68f653c8c?s=96&d=mm&r=g","caption":"Stephan Spijkers"}}]}},"_links":{"self":[{"href":"https:\/\/pimvendors.com\/nl\/wp-json\/wp\/v2\/posts\/14660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pimvendors.com\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pimvendors.com\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pimvendors.com\/nl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/pimvendors.com\/nl\/wp-json\/wp\/v2\/comments?post=14660"}],"version-history":[{"count":0,"href":"https:\/\/pimvendors.com\/nl\/wp-json\/wp\/v2\/posts\/14660\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pimvendors.com\/nl\/wp-json\/wp\/v2\/media\/14652"}],"wp:attachment":[{"href":"https:\/\/pimvendors.com\/nl\/wp-json\/wp\/v2\/media?parent=14660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pimvendors.com\/nl\/wp-json\/wp\/v2\/categories?post=14660"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pimvendors.com\/nl\/wp-json\/wp\/v2\/tags?post=14660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}